{"id":798,"date":"2014-02-06T14:28:30","date_gmt":"2014-02-06T13:28:30","guid":{"rendered":"https:\/\/nueva.torramosaicoshidraulicos.es\/baldosa-hidraulica\/baldosa-hidraulica-cenefa-ref-050-adg\/"},"modified":"2026-04-28T14:26:40","modified_gmt":"2026-04-28T13:26:40","slug":"rajola-hidraulica-sanefa-050","status":"publish","type":"product","link":"https:\/\/mosaicstorra.com\/ca\/productos\/baldosa-hidraulica-cenefa-050\/","title":{"rendered":"Rajola Hidr\u00e0ulica 050 (ADG)"},"content":{"rendered":"<p><strong>L\u00ednia: <\/strong>Rajola Hidr\u00e0ulica l\u00ednia Stock<\/p>\n<p><strong>Col\u00b7lecci\u00f3: <\/strong>Sanefa Ref 050 (A,D,G)<\/p>","protected":false},"excerpt":{"rendered":"<p>L\u00ednia: Rajola Hidr\u00e0ulica l\u00ednia Stock Col\u00b7lecci\u00f3: Sanefa Ref 050 (A,D,G)<\/p>","protected":false},"featured_media":28862,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[675,1542],"product_tag":[],"class_list":{"0":"post-798","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-cenefas","7":"product_cat-color-gris","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Baldosa Hidr\u00e1ulica 050 (A-D-G) - Mosaics Torra - Suelos Hidr\u00e1ulicos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mosaicstorra.com\/ca\/productes\/rajola-hidraulica-sanefa-050\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Baldosa Hidr\u00e1ulica 050 (A-D-G) - Mosaics Torra - Suelos Hidr\u00e1ulicos\" \/>\n<meta property=\"og:description\" content=\"L\u00ednea: Baldosa Hidr\u00e1ulica l\u00ednia Stock Colecci\u00f3n: Cenefa Ref 050 (A,D,G)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mosaicstorra.com\/ca\/productes\/rajola-hidraulica-sanefa-050\/\" \/>\n<meta property=\"og:site_name\" content=\"Mosaics Torra - Suelos Hidr\u00e1ulicos\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-28T13:26:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mosaicstorra.com\/wp-content\/uploads\/2025\/03\/baldosa-hidraulica-cenefa-050.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2480\" \/>\n\t<meta property=\"og:image:height\" content=\"2480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mosaicstorra.com\\\/productos\\\/baldosa-hidraulica-cenefa-050\\\/\",\"url\":\"https:\\\/\\\/mosaicstorra.com\\\/productos\\\/baldosa-hidraulica-cenefa-050\\\/\",\"name\":\"Baldosa Hidr\u00e1ulica 050 (A-D-G) - Mosaics Torra - Suelos Hidr\u00e1ulicos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mosaicstorra.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mosaicstorra.com\\\/productos\\\/baldosa-hidraulica-cenefa-050\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mosaicstorra.com\\\/productos\\\/baldosa-hidraulica-cenefa-050\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mosaicstorra.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/baldosa-hidraulica-cenefa-050.webp\",\"datePublished\":\"2014-02-06T13:28:30+00:00\",\"dateModified\":\"2026-04-28T13:26:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mosaicstorra.com\\\/productos\\\/baldosa-hidraulica-cenefa-050\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mosaicstorra.com\\\/productos\\\/baldosa-hidraulica-cenefa-050\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/mosaicstorra.com\\\/productos\\\/baldosa-hidraulica-cenefa-050\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mosaicstorra.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/baldosa-hidraulica-cenefa-050.webp\",\"contentUrl\":\"https:\\\/\\\/mosaicstorra.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/baldosa-hidraulica-cenefa-050.webp\",\"width\":2480,\"height\":2480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mosaicstorra.com\\\/productos\\\/baldosa-hidraulica-cenefa-050\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/mosaicstorra.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/mosaicstorra.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Baldosa Hidr\u00e1ulica 050 (A-D-G)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mosaicstorra.com\\\/#website\",\"url\":\"https:\\\/\\\/mosaicstorra.com\\\/\",\"name\":\"Mosaics Torra - Suelos Hidr\u00e1ulicos\",\"description\":\"Baldosas que cuentan historias\",\"publisher\":{\"@id\":\"https:\\\/\\\/mosaicstorra.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mosaicstorra.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mosaicstorra.com\\\/#organization\",\"name\":\"Mosaics Torra - Suelos Hidr\u00e1ulicos\",\"url\":\"https:\\\/\\\/mosaicstorra.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/mosaicstorra.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mosaicstorra.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-logo_wo_bcn.png\",\"contentUrl\":\"https:\\\/\\\/mosaicstorra.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-logo_wo_bcn.png\",\"width\":205,\"height\":77,\"caption\":\"Mosaics Torra - Suelos Hidr\u00e1ulicos\"},\"image\":{\"@id\":\"https:\\\/\\\/mosaicstorra.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rajola Hidr\u00e0ulica 050 (ADG) - Mosaics Torra - S\u00f2ls Hidr\u00e0ulics","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mosaicstorra.com\/ca\/productes\/rajola-hidraulica-sanefa-050\/","og_locale":"ca_ES","og_type":"article","og_title":"Baldosa Hidr\u00e1ulica 050 (A-D-G) - Mosaics Torra - Suelos Hidr\u00e1ulicos","og_description":"L\u00ednea: Baldosa Hidr\u00e1ulica l\u00ednia Stock Colecci\u00f3n: Cenefa Ref 050 (A,D,G)","og_url":"https:\/\/mosaicstorra.com\/ca\/productes\/rajola-hidraulica-sanefa-050\/","og_site_name":"Mosaics Torra - Suelos Hidr\u00e1ulicos","article_modified_time":"2026-04-28T13:26:40+00:00","og_image":[{"width":2480,"height":2480,"url":"https:\/\/mosaicstorra.com\/wp-content\/uploads\/2025\/03\/baldosa-hidraulica-cenefa-050.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mosaicstorra.com\/productos\/baldosa-hidraulica-cenefa-050\/","url":"https:\/\/mosaicstorra.com\/productos\/baldosa-hidraulica-cenefa-050\/","name":"Rajola Hidr\u00e0ulica 050 (ADG) - Mosaics Torra - S\u00f2ls Hidr\u00e0ulics","isPartOf":{"@id":"https:\/\/mosaicstorra.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mosaicstorra.com\/productos\/baldosa-hidraulica-cenefa-050\/#primaryimage"},"image":{"@id":"https:\/\/mosaicstorra.com\/productos\/baldosa-hidraulica-cenefa-050\/#primaryimage"},"thumbnailUrl":"https:\/\/mosaicstorra.com\/wp-content\/uploads\/2025\/03\/baldosa-hidraulica-cenefa-050.webp","datePublished":"2014-02-06T13:28:30+00:00","dateModified":"2026-04-28T13:26:40+00:00","breadcrumb":{"@id":"https:\/\/mosaicstorra.com\/productos\/baldosa-hidraulica-cenefa-050\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mosaicstorra.com\/productos\/baldosa-hidraulica-cenefa-050\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/mosaicstorra.com\/productos\/baldosa-hidraulica-cenefa-050\/#primaryimage","url":"https:\/\/mosaicstorra.com\/wp-content\/uploads\/2025\/03\/baldosa-hidraulica-cenefa-050.webp","contentUrl":"https:\/\/mosaicstorra.com\/wp-content\/uploads\/2025\/03\/baldosa-hidraulica-cenefa-050.webp","width":2480,"height":2480},{"@type":"BreadcrumbList","@id":"https:\/\/mosaicstorra.com\/productos\/baldosa-hidraulica-cenefa-050\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/mosaicstorra.com\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/mosaicstorra.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Baldosa Hidr\u00e1ulica 050 (A-D-G)"}]},{"@type":"WebSite","@id":"https:\/\/mosaicstorra.com\/#website","url":"https:\/\/mosaicstorra.com\/","name":"Mosaics Torra - Mosaics Hidr\u00e0ulics","description":"Rajoles que expliquen hist\u00f2ries","publisher":{"@id":"https:\/\/mosaicstorra.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mosaicstorra.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/mosaicstorra.com\/#organization","name":"Mosaics Torra - Mosaics Hidr\u00e0ulics","url":"https:\/\/mosaicstorra.com\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/mosaicstorra.com\/#\/schema\/logo\/image\/","url":"https:\/\/mosaicstorra.com\/wp-content\/uploads\/2024\/11\/cropped-logo_wo_bcn.png","contentUrl":"https:\/\/mosaicstorra.com\/wp-content\/uploads\/2024\/11\/cropped-logo_wo_bcn.png","width":205,"height":77,"caption":"Mosaics Torra - Suelos Hidr\u00e1ulicos"},"image":{"@id":"https:\/\/mosaicstorra.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mosaicstorra.com\/ca\/wp-json\/wp\/v2\/product\/798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mosaicstorra.com\/ca\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mosaicstorra.com\/ca\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/mosaicstorra.com\/ca\/wp-json\/wp\/v2\/comments?post=798"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mosaicstorra.com\/ca\/wp-json\/wp\/v2\/media\/28862"}],"wp:attachment":[{"href":"https:\/\/mosaicstorra.com\/ca\/wp-json\/wp\/v2\/media?parent=798"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mosaicstorra.com\/ca\/wp-json\/wp\/v2\/product_brand?post=798"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mosaicstorra.com\/ca\/wp-json\/wp\/v2\/product_cat?post=798"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mosaicstorra.com\/ca\/wp-json\/wp\/v2\/product_tag?post=798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}