{"id":1600,"count":14,"description":"","link":"https:\/\/mosaicstorra.com\/fr\/tienda\/baldosas-hidraulicas\/20x20-monocolor\/","name":"Couleur unie 20x20","slug":"couleur-unie-20x20","taxonomy":"product_cat","parent":1639,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Monocolor 20x20 - Mosaics Torra - Suelos Hidr\u00e1ulicos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mosaicstorra.com\/fr\/eshop\/nos-carreaux-de-ciment\/couleur-unie-20x20\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Monocolor 20x20 - Mosaics Torra - Suelos Hidr\u00e1ulicos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mosaicstorra.com\/fr\/eshop\/nos-carreaux-de-ciment\/couleur-unie-20x20\/\" \/>\n<meta property=\"og:site_name\" content=\"Mosaics Torra - Suelos Hidr\u00e1ulicos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/mosaicstorra.com\\\/en\\\/tienda\\\/baldosas-hidraulicas\\\/20x20-monocolor\\\/\",\"url\":\"https:\\\/\\\/mosaicstorra.com\\\/en\\\/tienda\\\/baldosas-hidraulicas\\\/20x20-monocolor\\\/\",\"name\":\"Monocolor 20x20 - Mosaics Torra - Suelos Hidr\u00e1ulicos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mosaicstorra.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mosaicstorra.com\\\/en\\\/tienda\\\/baldosas-hidraulicas\\\/20x20-monocolor\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mosaicstorra.com\\\/en\\\/tienda\\\/baldosas-hidraulicas\\\/20x20-monocolor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/mosaicstorra.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Baldosas Hidr\u00e1ulicas\",\"item\":\"https:\\\/\\\/mosaicstorra.com\\\/en\\\/tienda\\\/baldosas-hidraulicas\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Monocolor 20x20\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mosaicstorra.com\\\/#website\",\"url\":\"https:\\\/\\\/mosaicstorra.com\\\/\",\"name\":\"Mosaics Torra - Suelos Hidr\u00e1ulicos\",\"description\":\"Baldosas que cuentan historias\",\"publisher\":{\"@id\":\"https:\\\/\\\/mosaicstorra.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mosaicstorra.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mosaicstorra.com\\\/#organization\",\"name\":\"Mosaics Torra - Suelos Hidr\u00e1ulicos\",\"url\":\"https:\\\/\\\/mosaicstorra.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mosaicstorra.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mosaicstorra.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-logo_wo_bcn.png\",\"contentUrl\":\"https:\\\/\\\/mosaicstorra.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/cropped-logo_wo_bcn.png\",\"width\":205,\"height\":77,\"caption\":\"Mosaics Torra - Suelos Hidr\u00e1ulicos\"},\"image\":{\"@id\":\"https:\\\/\\\/mosaicstorra.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"foundingDate\":\"1975\",\"telephone\":\"+34 93 806 92 39\",\"email\":\"info@mosaicstorra.com\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Carrer de D\u00e9u i Mata, 62\",\"addressLocality\":\"Barcelona\",\"postalCode\":\"08029\",\"addressRegion\":\"Barcelona\",\"addressCountry\":\"ES\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/mosaicstorra\",\"https:\\\/\\\/www.facebook.com\\\/mosaicstorra\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Monocolor 20x20 - Mosa\u00efques Torra - Carreaux de Ciment","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mosaicstorra.com\/fr\/eshop\/nos-carreaux-de-ciment\/couleur-unie-20x20\/","og_locale":"fr_FR","og_type":"article","og_title":"Monocolor 20x20 - Mosaics Torra - Suelos Hidr\u00e1ulicos","og_url":"https:\/\/mosaicstorra.com\/fr\/eshop\/nos-carreaux-de-ciment\/couleur-unie-20x20\/","og_site_name":"Mosaics Torra - Suelos Hidr\u00e1ulicos","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/mosaicstorra.com\/en\/tienda\/baldosas-hidraulicas\/20x20-monocolor\/","url":"https:\/\/mosaicstorra.com\/en\/tienda\/baldosas-hidraulicas\/20x20-monocolor\/","name":"Monocolor 20x20 - Mosa\u00efques Torra - Carreaux de Ciment","isPartOf":{"@id":"https:\/\/mosaicstorra.com\/#website"},"breadcrumb":{"@id":"https:\/\/mosaicstorra.com\/en\/tienda\/baldosas-hidraulicas\/20x20-monocolor\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/mosaicstorra.com\/en\/tienda\/baldosas-hidraulicas\/20x20-monocolor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/mosaicstorra.com\/"},{"@type":"ListItem","position":2,"name":"Baldosas Hidr\u00e1ulicas","item":"https:\/\/mosaicstorra.com\/en\/tienda\/baldosas-hidraulicas\/"},{"@type":"ListItem","position":3,"name":"Monocolor 20x20"}]},{"@type":"WebSite","@id":"https:\/\/mosaicstorra.com\/#website","url":"https:\/\/mosaicstorra.com\/","name":"Mosaics Torra \u2013 Carreaux de ciment","description":"Des carreaux qui racontent des histoires","publisher":{"@id":"https:\/\/mosaicstorra.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mosaicstorra.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mosaicstorra.com\/#organization","name":"Mosaics Torra \u2013 Carreaux de ciment","url":"https:\/\/mosaicstorra.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mosaicstorra.com\/#\/schema\/logo\/image\/","url":"https:\/\/mosaicstorra.com\/wp-content\/uploads\/2024\/11\/cropped-logo_wo_bcn.png","contentUrl":"https:\/\/mosaicstorra.com\/wp-content\/uploads\/2024\/11\/cropped-logo_wo_bcn.png","width":205,"height":77,"caption":"Mosaics Torra - Suelos Hidr\u00e1ulicos"},"image":{"@id":"https:\/\/mosaicstorra.com\/#\/schema\/logo\/image\/"},"foundingDate":"1975","telephone":"+34 93 806 92 39","email":"info@mosaicstorra.com","address":{"@type":"PostalAddress","streetAddress":"Carrer de D\u00e9u i Mata, 62","addressLocality":"Barcelona","postalCode":"08029","addressRegion":"Barcelona","addressCountry":"ES"},"sameAs":["https:\/\/www.instagram.com\/mosaicstorra","https:\/\/www.facebook.com\/mosaicstorra"]}]}},"_links":{"self":[{"href":"https:\/\/mosaicstorra.com\/fr\/wp-json\/wp\/v2\/product_cat\/1600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mosaicstorra.com\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/mosaicstorra.com\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/mosaicstorra.com\/fr\/wp-json\/wp\/v2\/product_cat\/1639"}],"wp:post_type":[{"href":"https:\/\/mosaicstorra.com\/fr\/wp-json\/wp\/v2\/product?product_cat=1600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}